{"id":1,"date":"2019-08-29T15:47:08","date_gmt":"2019-08-29T13:47:08","guid":{"rendered":"http:\/\/initiative-wriezener-bahn.de\/?p=1"},"modified":"2021-01-14T09:58:15","modified_gmt":"2021-01-14T08:58:15","slug":"hallo-welt","status":"publish","type":"post","link":"https:\/\/initiative-wriezener-bahn.de\/index.php\/hallo-welt\/","title":{"rendered":"Verwaltungsspitzen beziehen Stellung pro Wriezener Bahn"},"content":{"rendered":"\n<p>Vor wenigen Tagen haben die Verwaltungsspitzen von Bad Freienwalde, Wriezen, Tiefensee, Wenreuchen, Ahrensfelde und den \u00c4mtern Falkenberg-H\u00f6he und Barnim-Oderbruch eine gemeinsame Willensbekundung unterzeichnet, mit der sie die Anbindung der Metropolregion an Berlin unterst\u00fctzen wollen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor wenigen Tagen haben die Verwaltungsspitzen von Bad Freienwalde, Wriezen, Tiefensee, Wenreuchen, Ahrensfelde und den \u00c4mtern Falkenberg-H\u00f6he und Barnim-Oderbruch eine gemeinsame Willensbekundung unterzeichnet, mit der sie die Anbindung der Metropolregion an Berlin unterst\u00fctzen wollen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}