{"id":239,"date":"2020-08-21T15:44:26","date_gmt":"2020-08-21T13:44:26","guid":{"rendered":"https:\/\/initiative-wriezener-bahn.de\/?p=239"},"modified":"2023-06-23T16:18:46","modified_gmt":"2023-06-23T14:18:46","slug":"roundtable-mit-landtagsabgeordneten-und-buergermeister","status":"publish","type":"post","link":"https:\/\/initiative-wriezener-bahn.de\/index.php\/roundtable-mit-landtagsabgeordneten-und-buergermeister\/","title":{"rendered":"Roundtable mit Landtagsabgeordneten und B\u00fcrgermeister"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"239\" class=\"elementor elementor-239\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd018c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd018c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e41d128\" data-id=\"e41d128\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d360636 elementor-widget elementor-widget-heading\" data-id=\"d360636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Roundtable mit Landtagsabgeordneten und B\u00fcrgermeister <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b80f149 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b80f149\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b7c9b2\" data-id=\"2b7c9b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ee7057 elementor-widget elementor-widget-image\" data-id=\"9ee7057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"421\" src=\"https:\/\/initiative-wriezener-bahn.de\/wp-content\/uploads\/2020\/08\/Damus_Rostock_Ilm.jpg\" class=\"attachment-large size-large wp-image-241\" alt=\"\" srcset=\"https:\/\/initiative-wriezener-bahn.de\/wp-content\/uploads\/2020\/08\/Damus_Rostock_Ilm.jpg 960w, https:\/\/initiative-wriezener-bahn.de\/wp-content\/uploads\/2020\/08\/Damus_Rostock_Ilm-300x168.jpg 300w, https:\/\/initiative-wriezener-bahn.de\/wp-content\/uploads\/2020\/08\/Damus_Rostock_Ilm-768x431.jpg 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Treffen vor Ort: Burkhardt Leue, stell. Vorsitzender IWB e.V., B\u00fcrgermeister Karsten Ilm, Steffen Blunk, Vorsitzender IWB e.V., Anne Blunk, B\u00fcndnis 90\/Die Gr\u00fcnen Ortsverbandssprecherin, Ilka Kr\u00fcger, Tourismuschefin Bad Freienwalde, Clemens Rostock, verkehrspolitischer Sprecher von B\u00fcndnis 90\/ Die Gr\u00fcnen im Landtag, Sahra Damus, MdL B\u00fcndnis 90\/Die Gr\u00fcnen (v.l.n.r.)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c27ea9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c27ea9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e512710\" data-id=\"e512710\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7895357 elementor-widget elementor-widget-text-editor\" data-id=\"7895357\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Am 31. Juli trafen wir mit den gr\u00fcnen Landtagsabgeordneten Sahra Damus und Clemes Rostock zu einem Gespr\u00e4ch \u00fcber die Wriezener Bahn im B\u00fcro des Wriezener B\u00fcrgermeisters Karsten Ilm zusammen.<\/p><p>Die beiden Landtagsabgeordneten wollten sich \u00fcber den aktuellen Stand der Reaktivierungsbem\u00fchungen vor Ort informieren. B\u00fcrgermeister Karsten Ilm betonte, wie wichtig es sei, dass die Verwaltungsspitzen von Kreis, Bad Freienwalde, den \u00c4mtern Barnim-Oderbruch und Falkenberg-H\u00f6he an einem Strang ziehen. Die Tatsache, dass sich mit der Initiative Wriezener Bahn e.V. ein b\u00fcrgerschaftliches Engagement entwickle, dass zudem als Moderationsplattform f\u00fcr alle an der Reaktivierung Beteiligten und Interessierten diene, begr\u00fc\u00dfte er ausdr\u00fccklich.<\/p><p>Als Vereinsvorsitzender habe ich erl\u00e4utert, dass wir es f\u00fcr dringend erforderlich halten, m\u00f6glichst schnell \u2013 deutlich vor dem Beginn der Nahverkehrsplanung 2023 des Landtages \u2013 eine Machbarkeitsstudie in Auftrag zu geben. Aus meiner Sicht ist die angedachte Vorgehensweise des Landes \u2013 ab 2023 zun\u00e4chst alle Bahnstrecken in Brandenburg einer Begutachtung zu unterziehen, um dann f\u00fcr einzelne Strecken im n\u00e4chsten Schritt eine Machbarkeitsstudie zu erstellen \u2013 wesentlich zu langsam und w\u00fcrde uns bei der Reaktivierung der Wriezener Bahn mehrere Jahre kosten.<\/p><p>Auf Seiten der Landtagsabgeordneten und auf Seiten des B\u00fcrgermeisters st\u00f6\u00dft unsere Argumentation auf offene Ohren.<br \/><br \/>Siehe auch: <a href=\"https:\/\/www.moz.de\/artikel-ansicht\/dg\/0\/1\/1818479\/\" target=\"_blank\" rel=\"noopener\">Artikel in der M\u00e4rkischen Oderzeitung vom 6. August 2020<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Am 31. Juli trafen wir mit den gr\u00fcnen Landtagsabgeordneten Sahra Damus und Clemes Rostock zu einem Gespr\u00e4ch \u00fcber die Wriezener Bahn im B\u00fcro des Wriezener B\u00fcrgermeisters Karsten Ilm zusammen.<\/p>\n","protected":false},"author":1,"featured_media":241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"jetpack_featured_media_url":"https:\/\/initiative-wriezener-bahn.de\/wp-content\/uploads\/2020\/08\/Damus_Rostock_Ilm.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts\/239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":4,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts\/239\/revisions"}],"predecessor-version":[{"id":769,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/posts\/239\/revisions\/769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/media\/241"}],"wp:attachment":[{"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/media?parent=239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/categories?post=239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/initiative-wriezener-bahn.de\/index.php\/wp-json\/wp\/v2\/tags?post=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}